{"id":1534,"date":"2017-04-12T11:29:01","date_gmt":"2017-04-12T15:29:01","guid":{"rendered":"http:\/\/www3.infodev.ca\/transit\/automatic-passenger-counting\/"},"modified":"2024-03-06T09:25:09","modified_gmt":"2024-03-06T14:25:09","slug":"comptage-automatique-passagers","status":"publish","type":"page","link":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/","title":{"rendered":"Comptage Automatique de Passagers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1534\" class=\"elementor elementor-1534 elementor-19\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-oyu01ko elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"oyu01ko\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-pxtk7hb\" data-id=\"pxtk7hb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-l6b105s elementor-widget elementor-widget-heading\" data-id=\"l6b105s\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-large\">Pourquoi compter les passagers?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-qqvi2ga elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"qqvi2ga\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-k4lwwhh\" data-id=\"k4lwwhh\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1xzi9ri elementor-widget elementor-widget-text-editor\" data-id=\"1xzi9ri\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Un syst\u00e8me de comptage automatique de passagers aidera votre \u00e9quipe de direction \u00e0 <span style=\"color: #2172b7;\"><strong>am\u00e9liorer la planification et le taux d&rsquo;occupation<\/strong><\/span> de votre syst\u00e8me de transit. Un syst\u00e8me de comptage\u00a0automatique de passagers est un<span style=\"color: #2172b7;\"><strong> outil essentiel<\/strong><\/span> cr\u00e9er des rapports pr\u00e9cis sur l&rsquo;achalandage afin de r\u00e9affecter vos ressources pour r\u00e9pondre \u00e0 la demande r\u00e9elle<span lang=\"fr\">, ainsi que de<\/span><span style=\"color: #2172b7;\"><strong> surveiller et pr\u00e9voir les tendances d&rsquo;utilisation <\/strong><\/span><span lang=\"fr\">et d&rsquo;achalandage. <br \/><\/span><\/p><p style=\"text-align: left;\"><span lang=\"fr\">Notre <\/span>syst\u00e8me automatique de comptage de passagers vous communique avec pr\u00e9cision l&rsquo;achalandage au fil du temps afin de <span style=\"color: #2172b7;\"><strong>cr\u00e9er des rapports pr\u00e9cis sur l&rsquo;achalandage. <\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-nl1rnd4 elementor-widget elementor-widget-heading\" data-id=\"nl1rnd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Syst\u00e8me de comptage automatique des passagers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-qoej0n9 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"qoej0n9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mesurez le succ\u00e8s de votre agence avec des chiffres d'achalandage fiables<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rapports optimis\u00e9s pour les d\u00e9cideurs<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Optimisez les itin\u00e9raires en fonction de l\u2019achalandage pr\u00e9cis.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Passager par heure de revenu<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-507f2df elementor-widget elementor-widget-button\" data-id=\"507f2df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.infodev.ca\/fr\/produits\/da-series-capteurs-comptage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apprenez-en plus sur nos capteurs de comptage<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-855025a elementor-widget elementor-widget-button\" data-id=\"855025a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.infodev.ca\/fr\/produits\/gateway-series\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apprenez-en plus sur nos ordinateurs de comptage<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ay5g397\" data-id=\"ay5g397\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e3dca7 elementor-widget elementor-widget-image\" data-id=\"0e3dca7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/elementor\/thumbs\/Automatic-Passenger-Counting-Solutions-for-Trains-Transit-Infodev-EDI-neezxqmyil426dtfznprgcp6wxhngf6zinkugd8pqq.jpg\" title=\"Automatic-Passenger-Counting-Solutions-for-Trains\u2013Transit\u2013Infodev-EDI\" alt=\"Automatic passenger Counting for train and train stations - Infodev EDI inc.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-t3yu0b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"t3yu0b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cfdolc0\" data-id=\"cfdolc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-oqd64cp elementor-widget elementor-widget-heading\" data-id=\"oqd64cp\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantages des syst\u00e8mes d'Infodev<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-pli1xzp elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"pli1xzp\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-awqi08g\" data-id=\"awqi08g\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0l943m elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c0l943m\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Architecture simple, modulaire et flexible<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capteurs calibr\u00e9s en usine<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Installation simple et rapide<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-jbelmgy\" data-id=\"jbelmgy\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-nwkftnf elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"nwkftnf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Technologie de comptage de passagers la plus pr\u00e9cise du march\u00e9<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Petit, robuste et fiable<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Prix comp\u00e9titifs<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-xbvf5fc\" data-id=\"xbvf5fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-w1ni2xc elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"w1ni2xc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rapports optimis\u00e9s pour les d\u00e9cideurs<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Discrets et esth\u00e9tiques<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e9sistant aux actes de vandalisme<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1w2asav elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1w2asav\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-km9f8ly\" data-id=\"km9f8ly\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-tbf4cyq elementor-widget elementor-widget-heading\" data-id=\"tbf4cyq\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Donn\u00e9es en temps-r\u00e9el<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0lc98ze elementor-widget elementor-widget-text-editor\" data-id=\"0lc98ze\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes fiers d&rsquo;avoir mis en place <span style=\"color: #2172b7;\"><strong>la premi\u00e8re technologie de comptage automatique des passagers dans un compartiment en temps r\u00e9el dans le monde.<\/strong><\/span><\/p><div>Cette vid\u00e9o montre comment le client et les passagers ont accueilli favorablement les informations en temps r\u00e9el sur le taux d&rsquo;occupation de chaque compartiment.<\/div><div>L&rsquo;application pour smartphone est populaire car elle permet aux passagers de voir en temps r\u00e9el le taux d&rsquo;occupation de chaque partie du train entrant, ainsi que sur des \u00e9crans g\u00e9ants install\u00e9s sur chaque quai.<\/div><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-wsfkvzl elementor-align-center elementor-widget elementor-widget-button\" data-id=\"wsfkvzl\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.infodev.ca\/fr\/ns-etude-de-cas\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire notre \u00e9tude de cas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-vw8l290\" data-id=\"vw8l290\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-qd4n1lk elementor-widget elementor-widget-video\" data-id=\"qd4n1lk\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=gvKM158XSl4&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-wpsdniz elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"wpsdniz\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-n9r1ojr\" data-id=\"n9r1ojr\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-qp93tuq elementor-widget elementor-widget-spacer\" data-id=\"qp93tuq\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a92igon elementor-widget elementor-widget-heading\" data-id=\"a92igon\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produits standards ou sur mesure selon vos besoins\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-gx07nqu elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"gx07nqu\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">S'adapte \u00e0 toutes portes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Site de production interne<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Des couleurs qui s\u2019agence aux panneaux des portes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be92fa1 elementor-widget elementor-widget-button\" data-id=\"be92fa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.infodev.ca\/fr\/produits\/da-series-capteurs-comptage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrez nos capteurs de comptage<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cy5buuu\" data-id=\"cy5buuu\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a271mgz elementor-widget elementor-widget-spacer\" data-id=\"a271mgz\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-xhvudzf elementor-widget elementor-widget-image\" data-id=\"xhvudzf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/DA-400-Sensor-3-sensors-White-1-300x225.jpg\" class=\"attachment-medium size-medium wp-image-5199\" alt=\"DA-400 Sensor 3-sensors White Bolt on Design\" srcset=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/DA-400-Sensor-3-sensors-White-1-300x225.jpg 300w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/DA-400-Sensor-3-sensors-White-1-768x576.jpg 768w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/DA-400-Sensor-3-sensors-White-1-760x570.jpg 760w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/DA-400-Sensor-3-sensors-White-1-348x261.jpg 348w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/DA-400-Sensor-3-sensors-White-1.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">White color sensor blending in the background.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8duibg2\" data-id=\"8duibg2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-lb56cjs elementor-widget elementor-widget-spacer\" data-id=\"lb56cjs\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88y8fdt elementor-widget elementor-widget-image\" data-id=\"88y8fdt\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/Da-400-sensor-recess-installation-1-300x225.jpg\" class=\"attachment-medium size-medium wp-image-5200\" alt=\"Da-400 sensor, recess installation\" srcset=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/Da-400-sensor-recess-installation-1-300x225.jpg 300w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/Da-400-sensor-recess-installation-1-768x576.jpg 768w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/Da-400-sensor-recess-installation-1-760x570.jpg 760w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/Da-400-sensor-recess-installation-1-348x261.jpg 348w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2017\/12\/Da-400-sensor-recess-installation-1.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Recessed installation example<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-wujtxvn elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"wujtxvn\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bvhxrty\" data-id=\"bvhxrty\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-stgvxik elementor-widget elementor-widget-text-editor\" data-id=\"stgvxik\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0\u00bb <strong>Pr\u00e9cision de 97,5% \u00e0 99.5%<\/strong> sans facteur de correction dans un environnement non contr\u00f4l\u00e9\u00a0\u00bb<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61yfe0f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61yfe0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-641b791\" data-id=\"641b791\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12dcd29 elementor-widget elementor-widget-image\" data-id=\"12dcd29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/APC_EN_WEB_R2209.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/Cover-Brochures-APC-mix-1024x682.png\" class=\"attachment-large size-large wp-image-9881\" alt=\"Infodev&apos;s APC for Transit Brochure\" srcset=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/Cover-Brochures-APC-mix-1024x682.png 1024w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/Cover-Brochures-APC-mix-300x200.png 300w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/Cover-Brochures-APC-mix-768x512.png 768w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/Cover-Brochures-APC-mix-1536x1024.png 1536w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/Cover-Brochures-APC-mix-760x507.png 760w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/Cover-Brochures-APC-mix-348x232.png 348w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/Cover-Brochures-APC-mix.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c09c29 elementor-widget elementor-widget-heading\" data-id=\"3c09c29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/APC_EN_WEB_R2209.pdf\" target=\"_blank\"> Comptage Automatique De Passagers<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08e05a4 elementor-widget elementor-widget-heading\" data-id=\"08e05a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/APC_EN_WEB_R2209.pdf\" target=\"_blank\">Pour: Bus, Trains, M\u00e9tros, Tramways et Gares<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ae66d7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8ae66d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/09\/APC_EN_WEB_R2209.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cloud-download-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger PDF<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bff8533\" data-id=\"bff8533\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b2b9e5 elementor-widget elementor-widget-image\" data-id=\"4b2b9e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Brochure-software_R2210_EN_WEB.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Cover-Brochures-software-EN-1024x683.png\" class=\"attachment-large size-large wp-image-9909\" alt=\"\" srcset=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Cover-Brochures-software-EN-1024x683.png 1024w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Cover-Brochures-software-EN-300x200.png 300w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Cover-Brochures-software-EN-768x512.png 768w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Cover-Brochures-software-EN-1536x1024.png 1536w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Cover-Brochures-software-EN-2048x1365.png 2048w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Cover-Brochures-software-EN-760x507.png 760w, https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Cover-Brochures-software-EN-348x232.png 348w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2878cfb elementor-widget elementor-widget-heading\" data-id=\"2878cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Brochure-software_R2210_EN_WEB.pdf\" target=\"_blank\">Suite Logicielle Insoft<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97eac9e elementor-widget elementor-widget-heading\" data-id=\"97eac9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Brochure-software_R2210_EN_WEB.pdf\" target=\"_blank\">Pour agences de transport<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7dd7eb elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e7dd7eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2022\/10\/Brochure-software_R2210_EN_WEB.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cloud-download-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger PDF<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e082131 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e082131\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78c6c12a\" data-id=\"78c6c12a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1605dab8 elementor-widget elementor-widget-heading\" data-id=\"1605dab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Suggested reading<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa5331d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"aa5331d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c2d65e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c2d65e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-18c7bc70\" data-id=\"18c7bc70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74080090 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"74080090\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-grow\" href=\"https:\/\/www.infodev.ca\/fr\/a-propos\/demande-d-informations\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"fa fa-envelope-o\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request APC information<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-10ee6b7a\" data-id=\"10ee6b7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d8f4171 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2d8f4171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-grow\" href=\"https:\/\/www.infodev.ca\/fr\/transit\/systemes-transport-intelligent\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">(ITS) intelligent transport system<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pourquoi compter les passagers? Un syst\u00e8me de comptage automatique de passagers aidera votre \u00e9quipe de direction \u00e0 am\u00e9liorer la planification et le taux d&rsquo;occupation de votre syst\u00e8me de transit. Un syst\u00e8me de comptage\u00a0automatique de passagers est un outil essentiel cr\u00e9er des rapports pr\u00e9cis sur l&rsquo;achalandage afin de r\u00e9affecter vos ressources pour r\u00e9pondre \u00e0 la demande [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4789,"parent":1505,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-1534","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Infodev EDI inc - Solutions de Comptage Automatique de Passagers (CAP)<\/title>\n<meta name=\"description\" content=\"Les syst\u00e8mes de comptage automatique de passagers et leurs donn\u00e9es fournissent des informations cruciales pour la gestion de vos transports.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comptage Automatique de Passagers\" \/>\n<meta property=\"og:description\" content=\"Pourquoi compter les passagers? Un syst\u00e8me de comptage automatique de passagers aidera votre \u00e9quipe de direction \u00e0 am\u00e9liorer la planification et le taux\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/\" \/>\n<meta property=\"og:site_name\" content=\"Infodev EDI inc\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T14:25:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.infodev.ca\/wp-content\/uploads\/2018\/09\/Banner-Image-Landing-Page-Infodev-at-RVE_B.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1330\" \/>\n\t<meta property=\"og:image:height\" content=\"795\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/comptage-automatique-de-passagers\\\/comptage-automatique-passagers\\\/\",\"url\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/comptage-automatique-de-passagers\\\/comptage-automatique-passagers\\\/\",\"name\":\"Infodev EDI inc - Solutions de Comptage Automatique de Passagers (CAP)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/comptage-automatique-de-passagers\\\/comptage-automatique-passagers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/comptage-automatique-de-passagers\\\/comptage-automatique-passagers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.infodev.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Banner-Image-Landing-Page-Infodev-at-RVE_B.png\",\"datePublished\":\"2017-04-12T15:29:01+00:00\",\"dateModified\":\"2024-03-06T14:25:09+00:00\",\"description\":\"Les syst\u00e8mes de comptage automatique de passagers et leurs donn\u00e9es fournissent des informations cruciales pour la gestion de vos transports.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/comptage-automatique-de-passagers\\\/comptage-automatique-passagers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/comptage-automatique-de-passagers\\\/comptage-automatique-passagers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/comptage-automatique-de-passagers\\\/comptage-automatique-passagers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.infodev.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Banner-Image-Landing-Page-Infodev-at-RVE_B.png\",\"contentUrl\":\"https:\\\/\\\/www.infodev.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Banner-Image-Landing-Page-Infodev-at-RVE_B.png\",\"width\":1330,\"height\":795,\"caption\":\"Passengers boarding a train\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/comptage-automatique-de-passagers\\\/comptage-automatique-passagers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transport\",\"item\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/transit\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comptage Automatique de Passagers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/\",\"name\":\"Infodev EDI inc\",\"description\":\"Experts in APC solutions since 1993\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/#organization\",\"name\":\"Infodev Electronic Designers International inc.\",\"url\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.infodev.ca\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Logo-rond.png\",\"contentUrl\":\"https:\\\/\\\/www.infodev.ca\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Logo-rond.png\",\"width\":500,\"height\":501,\"caption\":\"Infodev Electronic Designers International inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.infodev.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company-beta\\\/157030\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Infodev EDI inc - Solutions de Comptage Automatique de Passagers (CAP)","description":"Les syst\u00e8mes de comptage automatique de passagers et leurs donn\u00e9es fournissent des informations cruciales pour la gestion de vos transports.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/","og_locale":"fr_FR","og_type":"article","og_title":"Comptage Automatique de Passagers","og_description":"Pourquoi compter les passagers? Un syst\u00e8me de comptage automatique de passagers aidera votre \u00e9quipe de direction \u00e0 am\u00e9liorer la planification et le taux","og_url":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/","og_site_name":"Infodev EDI inc","article_modified_time":"2024-03-06T14:25:09+00:00","og_image":[{"width":1330,"height":795,"url":"https:\/\/www.infodev.ca\/wp-content\/uploads\/2018\/09\/Banner-Image-Landing-Page-Infodev-at-RVE_B.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/","url":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/","name":"Infodev EDI inc - Solutions de Comptage Automatique de Passagers (CAP)","isPartOf":{"@id":"https:\/\/www.infodev.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/#primaryimage"},"image":{"@id":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.infodev.ca\/wp-content\/uploads\/2018\/09\/Banner-Image-Landing-Page-Infodev-at-RVE_B.png","datePublished":"2017-04-12T15:29:01+00:00","dateModified":"2024-03-06T14:25:09+00:00","description":"Les syst\u00e8mes de comptage automatique de passagers et leurs donn\u00e9es fournissent des informations cruciales pour la gestion de vos transports.","breadcrumb":{"@id":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/#primaryimage","url":"https:\/\/www.infodev.ca\/wp-content\/uploads\/2018\/09\/Banner-Image-Landing-Page-Infodev-at-RVE_B.png","contentUrl":"https:\/\/www.infodev.ca\/wp-content\/uploads\/2018\/09\/Banner-Image-Landing-Page-Infodev-at-RVE_B.png","width":1330,"height":795,"caption":"Passengers boarding a train"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infodev.ca\/fr\/comptage-automatique-de-passagers\/comptage-automatique-passagers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.infodev.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Transport","item":"https:\/\/www.infodev.ca\/fr\/transit\/"},{"@type":"ListItem","position":3,"name":"Comptage Automatique de Passagers"}]},{"@type":"WebSite","@id":"https:\/\/www.infodev.ca\/fr\/#website","url":"https:\/\/www.infodev.ca\/fr\/","name":"Infodev EDI inc","description":"Experts in APC solutions since 1993","publisher":{"@id":"https:\/\/www.infodev.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.infodev.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.infodev.ca\/fr\/#organization","name":"Infodev Electronic Designers International inc.","url":"https:\/\/www.infodev.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.infodev.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.infodev.ca\/wp-content\/uploads\/2026\/04\/Logo-rond.png","contentUrl":"https:\/\/www.infodev.ca\/wp-content\/uploads\/2026\/04\/Logo-rond.png","width":500,"height":501,"caption":"Infodev Electronic Designers International inc."},"image":{"@id":"https:\/\/www.infodev.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company-beta\/157030\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/pages\/1534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/comments?post=1534"}],"version-history":[{"count":82,"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/pages\/1534\/revisions"}],"predecessor-version":[{"id":12568,"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/pages\/1534\/revisions\/12568"}],"up":[{"embeddable":true,"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/pages\/1505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/media\/4789"}],"wp:attachment":[{"href":"https:\/\/www.infodev.ca\/fr\/wp-json\/wp\/v2\/media?parent=1534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}